{"id":2736,"date":"2024-06-25T18:33:35","date_gmt":"2024-06-25T16:33:35","guid":{"rendered":"https:\/\/hd-xxlprint.de\/?page_id=2736"},"modified":"2025-08-11T12:04:08","modified_gmt":"2025-08-11T10:04:08","slug":"3d","status":"publish","type":"page","link":"https:\/\/hd-xxlprint.de\/en\/3d\/","title":{"rendered":"3D"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; max_width=&#8220;100vw&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dnxte_image_accordion dnxte_accordion_height=&#8220;600px&#8220; dnxte_accordion_direction_tablet=&#8220;column&#8220; dnxte_accordion_direction_phone=&#8220;column&#8220; dnxte_accordion_direction_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dnxte_image_accordion_item dnxte_bg_img=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/06\/HD-Digitaldruck-Shooting-3D-Druck-22.jpg&#8220; dnxte_use_icon=&#8220;off&#8220; dnxte_use_icon_img=&#8220;off&#8220; dnxte_btn_show_hide=&#8220;off&#8220; dnxte_imga_title_margin=&#8220;|10%||10%|false|true&#8220; dnxte_imga_title_padding=&#8220;||||false|false&#8220; accordion_hover_overlay_color=&#8220;rgba(0,0,0,0.15)&#8220; dnxte_imga_title_margin_tablet=&#8220;|10%||10%|false|true&#8220; dnxte_imga_title_margin_phone=&#8220;|5%||5%|false|true&#8220; dnxte_imga_title_margin_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Strawford &#8211; Bold||||||||&#8220; header_font_size=&#8220;2em&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.8em&#8220; custom_padding=&#8220;||||false|false&#8220; header_font_size_tablet=&#8220;1.5em&#8220; header_font_size_phone=&#8220;1.5em&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_text_shadow_style=&#8220;preset3&#8243; global_colors_info=&#8220;{}&#8220;][\/dnxte_image_accordion_item][dnxte_image_accordion_item dnxte_bg_img=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07348.jpg&#8220; dnxte_use_icon=&#8220;off&#8220; dnxte_use_icon_img=&#8220;off&#8220; dnxte_btn_show_hide=&#8220;off&#8220; dnxte_imga_title_margin=&#8220;|10%||10%|false|true&#8220; dnxte_imga_title_padding=&#8220;||||false|false&#8220; accordion_hover_overlay_color=&#8220;rgba(0,0,0,0.15)&#8220; dnxte_imga_title_margin_tablet=&#8220;|10%||10%|false|true&#8220; dnxte_imga_title_margin_phone=&#8220;|5%||5%|false|true&#8220; dnxte_imga_title_margin_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Strawford &#8211; Bold||||||||&#8220; header_font_size=&#8220;2em&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.8em&#8220; custom_padding=&#8220;||||false|false&#8220; header_font_size_tablet=&#8220;1.5em&#8220; header_font_size_phone=&#8220;1.5em&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_text_shadow_style=&#8220;preset3&#8243; global_colors_info=&#8220;{}&#8220;][\/dnxte_image_accordion_item][dnxte_image_accordion_item dnxte_bg_img=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/06\/HD-Digitaldruck-Shooting-3D-Druck-23.jpg&#8220; dnxte_use_icon=&#8220;off&#8220; dnxte_use_icon_img=&#8220;off&#8220; dnxte_btn_show_hide=&#8220;off&#8220; dnxte_imga_title_margin=&#8220;|10%||10%|false|true&#8220; dnxte_imga_title_padding=&#8220;||||false|false&#8220; accordion_hover_overlay_color=&#8220;rgba(0,0,0,0.15)&#8220; dnxte_imga_title_margin_tablet=&#8220;|10%||10%|false|true&#8220; dnxte_imga_title_margin_phone=&#8220;|5%||5%|false|true&#8220; dnxte_imga_title_margin_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Strawford &#8211; Bold||||||||&#8220; header_font_size=&#8220;2em&#8220; header_letter_spacing=&#8220;1px&#8220; header_line_height=&#8220;1.8em&#8220; custom_padding=&#8220;||||false|false&#8220; header_font_size_tablet=&#8220;1.5em&#8220; header_font_size_phone=&#8220;1.5em&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_text_shadow_style=&#8220;preset3&#8243; global_colors_info=&#8220;{}&#8220;][\/dnxte_image_accordion_item][\/dnxte_image_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; module_id=&#8220;xxl-druck&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;3_5,2_5&#8243; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||50px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; custom_margin=&#8220;||10px||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>Die Zukunft der Fertigung<\/h2>\n<h1>3D\u2013Druck<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;100%&#8220; width_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220; width__hover_enabled=&#8220;off|desktop&#8220;]<\/p>\n<p>3D-Druck revolutioniert die Fertigungsindustrie und bietet unz\u00e4hlige M\u00f6glichkeiten, von der Prototypenentwicklung bis hin zur Serienproduktion. Diese Technologie erm\u00f6glicht es, komplexe Formen und Strukturen herzustellen, die mit traditionellen Methoden kaum umsetzbar w\u00e4ren. Dar\u00fcber hinaus tr\u00e4gt der 3D-Druck zur Nachhaltigkeit bei, da er Materialabf\u00e4lle reduziert und Ressourcen effizienter nutzt. Ob im Bereich des Ingenieurwesens oder der Kunst \u2013 die Einsatzm\u00f6glichkeiten sind nahezu unbegrenzt. Bei H&amp;D Digitaldruck sind wir stolz darauf, diese zukunftsweisende Technologie in unser Portfolio aufgenommen zu haben, um Ihnen innovative und ma\u00dfgeschneiderte L\u00f6sungen anzubieten.<\/p>\n<h3><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/06\/3d-1.png&#8220; title_text=&#8220;3d&#8220; module_class=&#8220;dp-floating&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;2_5,3_5&#8243; disabled_on=&#8220;off|off|on&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||50px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/06\/3d-1.png&#8220; title_text=&#8220;3d&#8220; module_class=&#8220;dp-floating&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; custom_margin=&#8220;||10px||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>Die Zukunft der Fertigung<\/h2>\n<h1>3D\u2013Druck<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.17.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;100%&#8220; width_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220; width__hover_enabled=&#8220;off|desktop&#8220;]<\/p>\n<p>3D-Druck revolutioniert die Fertigungsindustrie und bietet unz\u00e4hlige M\u00f6glichkeiten, von der Prototypenentwicklung bis hin zur Serienproduktion. Diese Technologie erm\u00f6glicht es, komplexe Formen und Strukturen herzustellen, die mit traditionellen Methoden kaum umsetzbar w\u00e4ren. Dar\u00fcber hinaus tr\u00e4gt der 3D-Druck zur Nachhaltigkeit bei, da er Materialabf\u00e4lle reduziert und Ressourcen effizienter nutzt. Ob im Bereich des Ingenieurwesens oder der Kunst \u2013 die Einsatzm\u00f6glichkeiten sind nahezu unbegrenzt. Bei H&amp;D Digitaldruck sind wir stolz darauf, diese zukunftsweisende Technologie in unser Portfolio aufgenommen zu haben, um Ihnen innovative und ma\u00dfgeschneiderte L\u00f6sungen anzubieten.<\/p>\n<h3><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;85%&#8220; width_phone=&#8220;85%&#8220; width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;||20px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_gallery gallery_ids=&#8220;2750,2749&#8243; fullwidth=&#8220;on&#8220; module_class=&#8220;lwp-arrow-color&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_gallery][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin: auto;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; text_line_height=&#8220;1.9em&#8220; header_3_line_height=&#8220;1.2em&#8220; custom_margin=&#8220;||15px||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; border_radii=&#8220;off|||30px|&#8220; border_color_left=&#8220;rgba(40,40,40,0.7)&#8220; global_colors_info=&#8220;{}&#8220; border_width_left__hover_enabled=&#8220;off|hover&#8220; border_width_left__hover=&#8220;2px&#8220; transform_styles__hover_enabled=&#8220;off|desktop&#8220; transform_scale__hover_enabled=&#8220;off|desktop&#8220; transform_translate__hover_enabled=&#8220;off|desktop&#8220; transform_rotate__hover_enabled=&#8220;off|desktop&#8220; transform_skew__hover_enabled=&#8220;off|desktop&#8220; transform_origin__hover_enabled=&#8220;off|desktop&#8220; custom_padding__hover_enabled=&#8220;off|hover&#8220; custom_padding__hover=&#8220;|||25px|false|false&#8220; box_shadow_color__hover_enabled=&#8220;on|desktop&#8220; box_shadow_color__hover=&#8220;rgba(0,0,0,0.2)&#8220; transform_translate__hover=&#8220;5px|5px&#8220;]<\/p>\n<h3>Fortschrittlichste Technik<\/h3>\n<p>Unsere 3D-Druckmaschine geh\u00f6rt zu den Fortschrittlichsten auf dem Markt. Mit einer beheizbaren Druckplatte (bis 110\u00b0C), einem Durchmesser von 1000 mm, sowie einer maximalen Druckh\u00f6he von 800 mm, bietet sie beispiellose Flexibilit\u00e4t und Pr\u00e4zision. Wir verwenden haupts\u00e4chlich ASA-Filament (Acrylester-Styrol-Acrylnitril), das f\u00fcr seine Stabilit\u00e4t und Witterungsbest\u00e4ndigkeit bekannt ist, wodurch es sich perfekt f\u00fcr den Einsatz im Au\u00dfenbereich eignet.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4MjUifX0=@&#8220; button_text=&#8220;Kontakt aufnehmen&#8220; button_alignment=&#8220;left&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_text_color=&#8220;#3b3b3d&#8220; button_bg_color=&#8220;RGBA(255,255,255,0)&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;0.4px&#8220; button_font=&#8220;Strawford Bold||||||||&#8220; button_icon=&#8220;&#x24;||divi||400&#8243; button_on_hover=&#8220;off&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px|0px||0px|false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;on|desktop&#8220; button_text_color__hover=&#8220;#939598&#8243; button_letter_spacing__hover_enabled=&#8220;off|desktop&#8220; button_letter_spacing__hover=&#8220;0.8px&#8220; button_text_shadow_color__hover_enabled=&#8220;on|desktop&#8220; button_text_shadow_color__hover=&#8220;rgba(0,0,0,0.1)&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;85%&#8220; width_phone=&#8220;85%&#8220; width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;||20px||false|false&#8220; custom_css_main_element=&#8220;margin: auto;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin: auto;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; text_line_height=&#8220;1.9em&#8220; header_3_line_height=&#8220;1.2em&#8220; custom_margin=&#8220;||15px||false|false&#8220; custom_padding=&#8220;||0px||false|false&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|||30px|&#8220; border_color_left=&#8220;rgba(40,40,40,0.7)&#8220; global_colors_info=&#8220;{}&#8220; border_width_left__hover_enabled=&#8220;off|hover&#8220; border_width_left__hover=&#8220;2px&#8220; transform_styles__hover_enabled=&#8220;off|desktop&#8220; transform_scale__hover_enabled=&#8220;off|desktop&#8220; transform_translate__hover_enabled=&#8220;off|desktop&#8220; transform_rotate__hover_enabled=&#8220;off|desktop&#8220; transform_skew__hover_enabled=&#8220;off|desktop&#8220; transform_origin__hover_enabled=&#8220;off|desktop&#8220; custom_padding__hover_enabled=&#8220;off|hover&#8220; custom_padding__hover=&#8220;|||25px|false|false&#8220; box_shadow_color__hover_enabled=&#8220;on|desktop&#8220; box_shadow_color__hover=&#8220;rgba(0,0,0,0.2)&#8220; transform_translate__hover=&#8220;5px|5px&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h3>Ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr Ihre Bed\u00fcrfnisse<\/h3>\n<p>Egal, welche Anforderungen Sie haben, wir finden die passende L\u00f6sung! Mit unserem 3D-Drucker k\u00f6nnen wir eine Vielzahl von Produkten herstellen. Ob individuelle Ersatzteile, kreative Kunstwerke, funktionale Prototypen oder ma\u00dfgeschneiderte Werbeelemente \u2013 die M\u00f6glichkeiten sind endlos. Lassen Sie uns gemeinsam Ihre Ideen verwirklichen und innovative, ma\u00dfgeschneiderte L\u00f6sungen entwickeln, die genau auf Ihre Bed\u00fcrfnisse zugeschnitten sind.<\/p>\n<h3><\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4MjUifX0=@&#8220; button_text=&#8220;Kontakt aufnehmen&#8220; button_alignment=&#8220;left&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_text_color=&#8220;#3b3b3d&#8220; button_bg_color=&#8220;RGBA(255,255,255,0)&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;0.4px&#8220; button_font=&#8220;Strawford Bold||||||||&#8220; button_icon=&#8220;&#x24;||divi||400&#8243; button_on_hover=&#8220;off&#8220; custom_margin=&#8220;0px||20px||false|false&#8220; custom_padding=&#8220;0px|0px||0px|false|false&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;on|desktop&#8220; button_text_color__hover=&#8220;#939598&#8243; button_letter_spacing__hover_enabled=&#8220;off|desktop&#8220; button_letter_spacing__hover=&#8220;0.8px&#8220; button_text_shadow_color__hover_enabled=&#8220;on|desktop&#8220; button_text_shadow_color__hover=&#8220;rgba(0,0,0,0.1)&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_gallery gallery_ids=&#8220;2784,2785&#8243; fullwidth=&#8220;on&#8220; disabled_on=&#8220;on|off|off&#8220; module_class=&#8220;lwp-arrow-color&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; module_id=&#8220;werbetechnik&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;85%&#8220; width_phone=&#8220;85%&#8220; width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;||20px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; custom_margin=&#8220;||10px||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>Ihr Weg zu uns<\/h2>\n<h1>Kontakt<\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; width=&#8220;70%&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;100%&#8220; width_last_edited=&#8220;on|phone&#8220; max_width=&#8220;680px&#8220; global_colors_info=&#8220;{}&#8220; width__hover_enabled=&#8220;off|desktop&#8220;]<\/p>\n<p>Z\u00f6gern Sie nicht und kontaktieren Sie uns. Wir finden f\u00fcr (fast) alles eine L\u00f6sung. Egal, ob am Telefon, bei einem Kaffee oder ganz klassisch per E-Mail. Machen Sie den ersten Schritt und wir melden uns schnellstm\u00f6glich bei Ihnen.<\/p>\n<p>[\/et_pb_text][wpforms_selector form_id=&#8220;3115&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;1000px&#8220; global_colors_info=&#8220;{}&#8220;][\/wpforms_selector][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07350.jpg&#8220; title_text=&#8220;DSC07350&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07344.jpg&#8220; title_text=&#8220;DSC07344&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07335.jpg&#8220; title_text=&#8220;DSC07335&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07349.jpg&#8220; title_text=&#8220;DSC07349&#8243; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Trenner&#8220; _builder_version=&#8220;4.24.0&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/01\/Trenner-1-scaled.jpg&#8220; parallax=&#8220;on&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row make_equal=&#8220;on&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;10px||10px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;2a58ed68-3482-4290-9ccb-abb91e5b525b&#8220; header_font=&#8220;||||||||&#8220; header_6_font=&#8220;Strawford Bold||||||||&#8220; header_6_text_color=&#8220;#FFFFFF&#8220; header_6_font_size=&#8220;1em&#8220; header_6_letter_spacing=&#8220;1px&#8220; header_6_line_height=&#8220;1.2em&#8220; custom_margin=&#8220;||20px||false|false&#8220; custom_css_main_element=&#8220;font-size: clamp(36px, 6vw, 80px);&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h6>Mehr, als nur<br \/>Digitaldruck.<\/h6>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE4MjUifX0=@&#8220; button_text=&#8220;Kontakt aufnehmen&#8220; button_alignment=&#8220;left&#8220; _builder_version=&#8220;4.27.4&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_text_color=&#8220;#FFFFFF&#8220; button_bg_color=&#8220;RGBA(255,255,255,0)&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;0.4px&#8220; button_font=&#8220;Strawford Bold||||||||&#8220; button_icon=&#8220;&#x24;||divi||400&#8243; button_on_hover=&#8220;off&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px|0px||5px|false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;on|hover&#8220; button_text_color__hover=&#8220;#939598&#8243; button_letter_spacing__hover_enabled=&#8220;off|desktop&#8220; button_letter_spacing__hover=&#8220;0.8px&#8220; button_text_shadow_color__hover_enabled=&#8220;on|desktop&#8220; button_text_shadow_color__hover=&#8220;rgba(0,0,0,0.1)&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dnxte_image_accordion dnxte_image_accordion_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte_image_accordion_wrapper\" data-accordion-type=\"on_hover\"  data-expand-last-item=\"off\">\r\n\t\t\t\t\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module dnxte_image_accordion_item dnxte_image_accordion_item_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div id=\"\" class=\"\">\r\n                <div class=\"dnxte_image_accordion_bg\"><\/div>\r\n                    <div class=\"dnxte_image_accordion_bg_hover\"><\/div>\r\n                    <div class=\"dnxte_image_accordion_child_content_wrapper dnxte-align-horizontal-center dnxte-align-vertical-center\">\r\n                        <div class=\"dnxte-accordion-content\" data-active-on-load=\"0\" data-accordion-expand=\"none\">\r\n                            \r\n                            \r\n                            \r\n                            <div class=\"dnxte-accordion-description\">\r\n                            \r\n                            <\/div>\r\n                            \r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module dnxte_image_accordion_item dnxte_image_accordion_item_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div id=\"\" class=\"\">\r\n                <div class=\"dnxte_image_accordion_bg\"><\/div>\r\n                    <div class=\"dnxte_image_accordion_bg_hover\"><\/div>\r\n                    <div class=\"dnxte_image_accordion_child_content_wrapper dnxte-align-horizontal-center dnxte-align-vertical-center\">\r\n                        <div class=\"dnxte-accordion-content\" data-active-on-load=\"0\" data-accordion-expand=\"none\">\r\n                            <div class=\"dnxte-accordion-image-icon\"><span class=\"et-pb-icon social_twitter et_pb_counters dnxte-imageacdion-social\">$<\/span><\/div>\r\n                            <div class=\"dnxte-icon-image-wrapper dnxte-accordion-image-image\"><img decoding=\"async\" src=\"\" class=\"dnxte-icon-image\" alt=\"\" \/><\/div>\r\n                            \r\n                            <div class=\"dnxte-accordion-description\">\r\n                            \r\n                            <\/div>\r\n                            <div class=\"dnxte-accordion-button-wrap\"><a href=\"\" class=\"dnxte_accordion_button\" target=\"_self\">Button Text<\/a><\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2736","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3D - H&amp;D Digitaldruck<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hd-xxlprint.de\/en\/3d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3D - H&amp;D Digitaldruck\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hd-xxlprint.de\/en\/3d\/\" \/>\n<meta property=\"og:site_name\" content=\"H&amp;D Digitaldruck\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T10:04:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"[dnxte_image_accordion dnxte_accordion_height=&quot;600px&quot; dnxte_accordion_direction_tablet=&quot;column&quot; dnxte_accordion_direction_phone=&quot;column&quot; dnxte_accordion_direction_last_edited=&quot;on|phone&quot; _builder_version=&quot;4.24.0&quot; _module_preset=&quot;default&quot; global_colors_info=&quot;{}&quot;][dnxte_image_accordion_item dnxte_bg_img=&quot;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/06\/HD-Digitaldruck-Shooting-3D-Druck-22.jpg&quot; dnxte_use_icon=&quot;off&quot; dnxte_use_icon_img=&quot;off&quot; dnxte_btn_show_hide=&quot;off&quot; dnxte_imga_title_margin=&quot;|10%||10%|false|true&quot; dnxte_imga_title_padding=&quot;||||false|false&quot; accordion_hover_overlay_color=&quot;rgba(0,0,0,0.15)&quot; dnxte_imga_title_margin_tablet=&quot;|10%||10%|false|true&quot; dnxte_imga_title_margin_phone=&quot;|5%||5%|false|true&quot; dnxte_imga_title_margin_last_edited=&quot;on|desktop&quot; _builder_version=&quot;4.24.0&quot; _module_preset=&quot;default&quot; header_font=&quot;Strawford - Bold||||||||&quot; header_font_size=&quot;2em&quot; header_letter_spacing=&quot;1px&quot; header_line_height=&quot;1.8em&quot; custom_padding=&quot;||||false|false&quot; header_font_size_tablet=&quot;1.5em&quot; header_font_size_phone=&quot;1.5em&quot; header_font_size_last_edited=&quot;on|phone&quot; header_text_shadow_style=&quot;preset3&quot; global_colors_info=&quot;{}&quot;][\/dnxte_image_accordion_item][dnxte_image_accordion_item dnxte_bg_img=&quot;https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07348.jpg&quot; dnxte_use_icon=&quot;off&quot; dnxte_use_icon_img=&quot;off&quot; dnxte_btn_show_hide=&quot;off&quot; dnxte_imga_title_margin=&quot;|10%||10%|false|true&quot; dnxte_imga_title_padding=&quot;||||false|false&quot; accordion_hover_overlay_color=&quot;rgba(0,0,0,0.15)&quot; dnxte_imga_title_margin_tablet=&quot;|10%||10%|false|true&quot; dnxte_imga_title_margin_phone=&quot;|5%||5%|false|true&quot; dnxte_imga_title_margin_last_edited=&quot;on|desktop&quot; _builder_version=&quot;4.24.0&quot; _module_preset=&quot;default&quot; header_font=&quot;Strawford - Bold||||||||&quot; header_font_size=&quot;2em&quot; header_letter_spacing=&quot;1px&quot; header_line_height=&quot;1.8em&quot; custom_padding=&quot;||||false|false&quot; header_font_size_tablet=&quot;1.5em&quot; header_font_size_phone=&quot;1.5em&quot; header_font_size_last_edited=&quot;on|phone&quot; header_text_shadow_style=&quot;preset3&quot; [&hellip;]\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hd-xxlprint.de\\\/3d\\\/\",\"url\":\"https:\\\/\\\/hd-xxlprint.de\\\/3d\\\/\",\"name\":\"3D - H&amp;D Digitaldruck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hd-xxlprint.de\\\/#website\"},\"datePublished\":\"2024-06-25T16:33:35+00:00\",\"dateModified\":\"2025-08-11T10:04:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hd-xxlprint.de\\\/3d\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hd-xxlprint.de\\\/3d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hd-xxlprint.de\\\/3d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hd-xxlprint.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hd-xxlprint.de\\\/#website\",\"url\":\"https:\\\/\\\/hd-xxlprint.de\\\/\",\"name\":\"H&amp;D Digitaldruck\",\"description\":\"Mehr, als nur Digitaldruck\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hd-xxlprint.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3D - H&amp;D Digitaldruck","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hd-xxlprint.de\/en\/3d\/","og_locale":"en_US","og_type":"article","og_title":"3D - H&amp;D Digitaldruck","og_url":"https:\/\/hd-xxlprint.de\/en\/3d\/","og_site_name":"H&amp;D Digitaldruck","article_modified_time":"2025-08-11T10:04:08+00:00","twitter_card":"summary_large_image","twitter_description":"[dnxte_image_accordion dnxte_accordion_height=\"600px\" dnxte_accordion_direction_tablet=\"column\" dnxte_accordion_direction_phone=\"column\" dnxte_accordion_direction_last_edited=\"on|phone\" _builder_version=\"4.24.0\" _module_preset=\"default\" global_colors_info=\"{}\"][dnxte_image_accordion_item dnxte_bg_img=\"https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/06\/HD-Digitaldruck-Shooting-3D-Druck-22.jpg\" dnxte_use_icon=\"off\" dnxte_use_icon_img=\"off\" dnxte_btn_show_hide=\"off\" dnxte_imga_title_margin=\"|10%||10%|false|true\" dnxte_imga_title_padding=\"||||false|false\" accordion_hover_overlay_color=\"rgba(0,0,0,0.15)\" dnxte_imga_title_margin_tablet=\"|10%||10%|false|true\" dnxte_imga_title_margin_phone=\"|5%||5%|false|true\" dnxte_imga_title_margin_last_edited=\"on|desktop\" _builder_version=\"4.24.0\" _module_preset=\"default\" header_font=\"Strawford - Bold||||||||\" header_font_size=\"2em\" header_letter_spacing=\"1px\" header_line_height=\"1.8em\" custom_padding=\"||||false|false\" header_font_size_tablet=\"1.5em\" header_font_size_phone=\"1.5em\" header_font_size_last_edited=\"on|phone\" header_text_shadow_style=\"preset3\" global_colors_info=\"{}\"][\/dnxte_image_accordion_item][dnxte_image_accordion_item dnxte_bg_img=\"https:\/\/hd-xxlprint.de\/wp-content\/uploads\/2024\/07\/DSC07348.jpg\" dnxte_use_icon=\"off\" dnxte_use_icon_img=\"off\" dnxte_btn_show_hide=\"off\" dnxte_imga_title_margin=\"|10%||10%|false|true\" dnxte_imga_title_padding=\"||||false|false\" accordion_hover_overlay_color=\"rgba(0,0,0,0.15)\" dnxte_imga_title_margin_tablet=\"|10%||10%|false|true\" dnxte_imga_title_margin_phone=\"|5%||5%|false|true\" dnxte_imga_title_margin_last_edited=\"on|desktop\" _builder_version=\"4.24.0\" _module_preset=\"default\" header_font=\"Strawford - Bold||||||||\" header_font_size=\"2em\" header_letter_spacing=\"1px\" header_line_height=\"1.8em\" custom_padding=\"||||false|false\" header_font_size_tablet=\"1.5em\" header_font_size_phone=\"1.5em\" header_font_size_last_edited=\"on|phone\" header_text_shadow_style=\"preset3\" [&hellip;]","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hd-xxlprint.de\/3d\/","url":"https:\/\/hd-xxlprint.de\/3d\/","name":"3D - H&amp;D Digitaldruck","isPartOf":{"@id":"https:\/\/hd-xxlprint.de\/#website"},"datePublished":"2024-06-25T16:33:35+00:00","dateModified":"2025-08-11T10:04:08+00:00","breadcrumb":{"@id":"https:\/\/hd-xxlprint.de\/3d\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hd-xxlprint.de\/3d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hd-xxlprint.de\/3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hd-xxlprint.de\/"},{"@type":"ListItem","position":2,"name":"3D"}]},{"@type":"WebSite","@id":"https:\/\/hd-xxlprint.de\/#website","url":"https:\/\/hd-xxlprint.de\/","name":"H&amp;D Digitaldruck","description":"Mehr, als nur Digitaldruck","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hd-xxlprint.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/pages\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/comments?post=2736"}],"version-history":[{"count":22,"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/pages\/2736\/revisions"}],"predecessor-version":[{"id":3177,"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/pages\/2736\/revisions\/3177"}],"wp:attachment":[{"href":"https:\/\/hd-xxlprint.de\/en\/wp-json\/wp\/v2\/media?parent=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}